{"id":3854,"date":"2023-03-15T06:04:27","date_gmt":"2023-03-15T10:04:27","guid":{"rendered":"https:\/\/worldvapersalliance.com\/?p=3854"},"modified":"2023-03-16T06:06:30","modified_gmt":"2023-03-16T10:06:30","slug":"gogolishvili-aromi-determinanti-per-smettere-di-fumare","status":"publish","type":"post","link":"https:\/\/worldvapersalliance.com\/sv\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\/","title":{"rendered":"Gogolishvili &quot;Aromi determinanti per smettere di fumare&quot;"},"content":{"rendered":"<p><em>&quot;Una nuova ricerca mostra ancora una volta che gli adulti preferiscono vari sapori piuttosto che essere limitati alla esclusiva scelta degli aromi a <span class=\"glossaryLink\" data-cmtooltip=\"Con il termine Base, o base neutra, indichiamo la miscela di Glicole Propilenico(PG) e Glicerina \/ Glicerolo Vegetale senza l'aggiunta di aromi. E' la base principale di tutti i liquidi per sigaretta elettronica. In base alle esigenze possiamo personalizzare la composizione della base per avere: aroma maggiore o maggiore fumosit\u00e0, cambiando semplicemente la proporzione di VG e PG. \">bas<\/span> di tabak.<br \/>\nI dibattiti sul divieto dei sapori di vaporizzazione sono in corso da anni, i particolare negli Stati Uniti, i Europa e i Kanada.<br \/>\nQuesti dibattiti hanno implicazioni significative per la riduzione del danno del tabacco, poich\u00e9 i vapori aromatizzati sono spesso preferiti dai fumatori che cercano di smettere di fumare\u201d. <\/em><\/p>\n<p>Lo sottolinea, attraverso le pagine della <strong>World Vapers&#039; Alliance<\/strong>, <strong>Mariam Gogolishvili<\/strong>, una dei protagonisti della struttura della <a href=\"https:\/\/www.svapomagazine.it\/la-world-vapers-alliance-consegna-raccomandazioni-al-governo-italiano\/\" target=\"_blank\" rel=\"noopener\">WVA<\/a> nonch\u00e8 esperta attivista gi\u00e0 operativa con diverse Ong in tutta Europa \u2013 tra le altre promotrice del movimento \u201cDo not arrest\u201d lanciato contro la politica repressiva sulle droghe leggere i Georgia.<br \/>\n&quot;<em>\u00c8 tempo di porre fine a questi dibattiti e concentrarsi su politiche basate sull&#039;evidenza che proteggano la salute pubblica preservando al contempo i benefici della THR<\/em> \u2013 prosegue la stessa \u2013<em> I responsabili politici dovrebbero considerare la ricerca disponibile sui prodotti da svapo aromatizzati ei loro potenziali benefici e rischi\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>L\u00e4s hela texten <a href=\"https:\/\/www.svapomagazine.it\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\/\" target=\"_blank\" rel=\"noopener\">h\u00e4r<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>\u201cUna nuova ricerca mostra ancora una volta che gli adulti preferiscono vari sapori piuttosto che essere limitati alla esclusiva scelta degli aromi a base di tabacco. I dibattiti sul divieto dei sapori di vaporizzazione sono in corso da anni, in particolare negli Stati Uniti, in Europa e in Canada. Questi dibattiti hanno implicazioni significative per [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6394,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-3854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wva-in-the-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gogolishvili \u201cAromi determinanti per smettere di fumare\u201d - World Vapers&#039; Alliance<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/worldvapersalliance.com\/sv\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\/\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gogolishvili \u201cAromi determinanti per smettere di fumare\u201d - World Vapers&#039; Alliance\" \/>\n<meta property=\"og:description\" content=\"\u201cUna nuova ricerca mostra ancora una volta che gli adulti preferiscono vari sapori piuttosto che essere limitati alla esclusiva scelta degli aromi a base di tabacco. I dibattiti sul divieto dei sapori di vaporizzazione sono in corso da anni, in particolare negli Stati Uniti, in Europa e in Canada. Questi dibattiti hanno implicazioni significative per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/worldvapersalliance.com\/sv\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\/\" \/>\n<meta property=\"og:site_name\" content=\"World Vapers&#039; Alliance\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-15T10:04:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-16T10:06:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2022\/09\/SVAPO-magazine.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2081\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"World Vapers&#039; Alliance\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Skriven av\" \/>\n\t<meta name=\"twitter:data1\" content=\"World Vapers&#039; Alliance\" \/>\n\t<meta name=\"twitter:label2\" content=\"Ber\u00e4knad l\u00e4stid\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\\\/\"},\"author\":{\"name\":\"World Vapers' Alliance\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#\\\/schema\\\/person\\\/18484a6f20bcc6f70a2419c8babe017d\"},\"headline\":\"Gogolishvili \u201cAromi determinanti per smettere di fumare\u201d\",\"datePublished\":\"2023-03-15T10:04:27+00:00\",\"dateModified\":\"2023-03-16T10:06:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\\\/\"},\"wordCount\":186,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WVA-in-the-news.png\",\"articleSection\":[\"WVA in the News\"],\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/worldvapersalliance.com\\\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\\\/\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\\\/\",\"name\":\"Gogolishvili \u201cAromi determinanti per smettere di fumare\u201d - World Vapers&#039; Alliance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WVA-in-the-news.png\",\"datePublished\":\"2023-03-15T10:04:27+00:00\",\"dateModified\":\"2023-03-16T10:06:30+00:00\",\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/worldvapersalliance.com\\\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sv-SE\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WVA-in-the-news.png\",\"contentUrl\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WVA-in-the-news.png\",\"width\":1264,\"height\":848},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#website\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/\",\"name\":\"World Vapers&#039; Alliance\",\"description\":\"The largest community of vapers\",\"publisher\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/worldvapersalliance.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sv-SE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#organization\",\"name\":\"World Vapers&#039; Alliance\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sv-SE\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WVA_RB_Fist_G.png\",\"contentUrl\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WVA_RB_Fist_G.png\",\"width\":985,\"height\":1177,\"caption\":\"World Vapers&#039; Alliance\"},\"image\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#\\\/schema\\\/person\\\/18484a6f20bcc6f70a2419c8babe017d\",\"name\":\"World Vapers' Alliance\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sv-SE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g\",\"caption\":\"World Vapers' Alliance\"},\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/sv\\\/author\\\/wva\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gogolishvili &quot;Aromi determinanti per smettere di fumare&quot; - World Vapers&#039; Alliance","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/worldvapersalliance.com\/sv\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\/","og_locale":"sv_SE","og_type":"article","og_title":"Gogolishvili \u201cAromi determinanti per smettere di fumare\u201d - World Vapers&#039; Alliance","og_description":"\u201cUna nuova ricerca mostra ancora una volta che gli adulti preferiscono vari sapori piuttosto che essere limitati alla esclusiva scelta degli aromi a base di tabacco. I dibattiti sul divieto dei sapori di vaporizzazione sono in corso da anni, in particolare negli Stati Uniti, in Europa e in Canada. Questi dibattiti hanno implicazioni significative per [&hellip;]","og_url":"https:\/\/worldvapersalliance.com\/sv\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\/","og_site_name":"World Vapers&#039; Alliance","article_published_time":"2023-03-15T10:04:27+00:00","article_modified_time":"2023-03-16T10:06:30+00:00","og_image":[{"width":2081,"height":1920,"url":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2022\/09\/SVAPO-magazine.png","type":"image\/png"}],"author":"World Vapers' Alliance","twitter_card":"summary_large_image","twitter_misc":{"Skriven av":"World Vapers' Alliance","Ber\u00e4knad l\u00e4stid":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/worldvapersalliance.com\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\/#article","isPartOf":{"@id":"https:\/\/worldvapersalliance.com\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\/"},"author":{"name":"World Vapers' Alliance","@id":"https:\/\/worldvapersalliance.com\/#\/schema\/person\/18484a6f20bcc6f70a2419c8babe017d"},"headline":"Gogolishvili \u201cAromi determinanti per smettere di fumare\u201d","datePublished":"2023-03-15T10:04:27+00:00","dateModified":"2023-03-16T10:06:30+00:00","mainEntityOfPage":{"@id":"https:\/\/worldvapersalliance.com\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\/"},"wordCount":186,"commentCount":0,"publisher":{"@id":"https:\/\/worldvapersalliance.com\/#organization"},"image":{"@id":"https:\/\/worldvapersalliance.com\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\/#primaryimage"},"thumbnailUrl":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2025\/08\/WVA-in-the-news.png","articleSection":["WVA in the News"],"inLanguage":"sv-SE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/worldvapersalliance.com\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/worldvapersalliance.com\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\/","url":"https:\/\/worldvapersalliance.com\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\/","name":"Gogolishvili &quot;Aromi determinanti per smettere di fumare&quot; - World Vapers&#039; Alliance","isPartOf":{"@id":"https:\/\/worldvapersalliance.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/worldvapersalliance.com\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\/#primaryimage"},"image":{"@id":"https:\/\/worldvapersalliance.com\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\/#primaryimage"},"thumbnailUrl":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2025\/08\/WVA-in-the-news.png","datePublished":"2023-03-15T10:04:27+00:00","dateModified":"2023-03-16T10:06:30+00:00","inLanguage":"sv-SE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/worldvapersalliance.com\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\/"]}]},{"@type":"ImageObject","inLanguage":"sv-SE","@id":"https:\/\/worldvapersalliance.com\/gogolishvili-aromi-determinanti-per-smettere-di-fumare\/#primaryimage","url":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2025\/08\/WVA-in-the-news.png","contentUrl":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2025\/08\/WVA-in-the-news.png","width":1264,"height":848},{"@type":"WebSite","@id":"https:\/\/worldvapersalliance.com\/#website","url":"https:\/\/worldvapersalliance.com\/","name":"World Vapers&#039; Alliance","description":"Den st\u00f6rsta gemenskapen av vapers","publisher":{"@id":"https:\/\/worldvapersalliance.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/worldvapersalliance.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sv-SE"},{"@type":"Organization","@id":"https:\/\/worldvapersalliance.com\/#organization","name":"World Vapers&#039; Alliance","url":"https:\/\/worldvapersalliance.com\/","logo":{"@type":"ImageObject","inLanguage":"sv-SE","@id":"https:\/\/worldvapersalliance.com\/#\/schema\/logo\/image\/","url":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2022\/01\/WVA_RB_Fist_G.png","contentUrl":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2022\/01\/WVA_RB_Fist_G.png","width":985,"height":1177,"caption":"World Vapers&#039; Alliance"},"image":{"@id":"https:\/\/worldvapersalliance.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/worldvapersalliance.com\/#\/schema\/person\/18484a6f20bcc6f70a2419c8babe017d","name":"World Vapers&#039; Alliance","image":{"@type":"ImageObject","inLanguage":"sv-SE","@id":"https:\/\/secure.gravatar.com\/avatar\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g","caption":"World Vapers' Alliance"},"url":"https:\/\/worldvapersalliance.com\/sv\/author\/wva\/"}]}},"_links":{"self":[{"href":"https:\/\/worldvapersalliance.com\/sv\/wp-json\/wp\/v2\/posts\/3854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/worldvapersalliance.com\/sv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/worldvapersalliance.com\/sv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/worldvapersalliance.com\/sv\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/worldvapersalliance.com\/sv\/wp-json\/wp\/v2\/comments?post=3854"}],"version-history":[{"count":0,"href":"https:\/\/worldvapersalliance.com\/sv\/wp-json\/wp\/v2\/posts\/3854\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/worldvapersalliance.com\/sv\/wp-json\/wp\/v2\/media\/6394"}],"wp:attachment":[{"href":"https:\/\/worldvapersalliance.com\/sv\/wp-json\/wp\/v2\/media?parent=3854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/worldvapersalliance.com\/sv\/wp-json\/wp\/v2\/categories?post=3854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/worldvapersalliance.com\/sv\/wp-json\/wp\/v2\/tags?post=3854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}