{"id":5333,"date":"2024-01-05T06:18:29","date_gmt":"2024-01-05T11:18:29","guid":{"rendered":"https:\/\/worldvapersalliance.com\/?p=5333"},"modified":"2024-01-22T06:24:52","modified_gmt":"2024-01-22T11:24:52","slug":"the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool","status":"publish","type":"post","link":"https:\/\/worldvapersalliance.com\/pt\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\/","title":{"rendered":"O Parlamento Europeu reconheceu oficialmente o vaping como uma forma de cessa\u00e7\u00e3o tab\u00e1gica\u2026"},"content":{"rendered":"<h4>Um relat\u00f3rio sobre Doen\u00e7as N\u00e3o Transmiss\u00edveis, elaborado pela Subcomiss\u00e3o de Sa\u00fade P\u00fablica da UE, reconheceu oficialmente a efic\u00e1cia do vaping como ferramenta para o abandono do tabagismo.<\/h4>\n<p>O Parlamento Europeu reconheceu oficialmente o papel substancial do vaping na cessa\u00e7\u00e3o tab\u00e1gica durante uma sess\u00e3o plen\u00e1ria, ap\u00f3s a aprova\u00e7\u00e3o dos produtos pela [empresa\/organiza\u00e7\u00e3o].<a href=\"https:\/\/www.europarl.europa.eu\/committees\/en\/sant\/home\/highlights\"> Subcomiss\u00e3o da UE para a Sa\u00fade P\u00fablica<\/a> (SANT) em 7 de novembro. Este desenvolvimento \u00e9 considerado um marco significativo no esfor\u00e7o para combater doen\u00e7as relacionadas ao tabagismo na Uni\u00e3o Europeia (UE), atrav\u00e9s da ado\u00e7\u00e3o da redu\u00e7\u00e3o de danos do tabaco (RDT).<\/p>\n<p>Como parte de uma iniciativa mais ampla do Parlamento sobre doen\u00e7as n\u00e3o transmiss\u00edveis, o relat\u00f3rio n\u00e3o s\u00f3 reconhece o uso de cigarros eletr\u00f4nicos como uma <a href=\"https:\/\/www.vapingpost.com\/2023\/09\/21\/study-finds-vapes-are-the-most-effective-quit-smoking-aids-followed-by-prescription-drugs\/\">m\u00e9todo eficaz para deixar de fumar<\/a> mas tamb\u00e9m dever\u00e1 influenciar a dire\u00e7\u00e3o das pol\u00edticas de sa\u00fade em toda a UE. No entanto, permanece um ponto de disc\u00f3rdia em rela\u00e7\u00e3o \u00e0 recomenda\u00e7\u00e3o inicial da SANT de restringir o uso de cigarros eletr\u00f4nicos em \u00e1reas p\u00fablicas espec\u00edficas.<\/p>\n<p>No entanto, o diretor da Alian\u00e7a Mundial de Cigarros Eletr\u00f4nicos (WVA), Michael Landl, considera o reconhecimento dos cigarros eletr\u00f4nicos um passo positivo, destacando uma mudan\u00e7a not\u00e1vel no reconhecimento do impacto positivo desses produtos na sa\u00fade p\u00fablica. Ele faz um apelo \u00e0 Comiss\u00e3o Europeia (CE), que permanece <a href=\"https:\/\/www.vapingpost.com\/2023\/10\/19\/is-the-european-commission-playing-dirty-to-push-its-nicotine-pouches-ban-agenda\/\">veementemente contra estrat\u00e9gias de THR<\/a>, Para estar em conson\u00e2ncia com essa perspectiva, ele enfatizou que essa aprova\u00e7\u00e3o representa a decis\u00e3o coletiva do Parlamento, os representantes diretos dos cidad\u00e3os da UE.<\/p>\n<p>Ao discutir esse desenvolvimento com Landl, numa tentativa de avaliar sua import\u00e2ncia, ele disse ao Vaping Post que, embora <a href=\"https:\/\/www.europarl.europa.eu\/doceo\/document\/A-9-2023-0366_EN.html\">Doen\u00e7as N\u00e3o Transmiss\u00edveis (DNT)<\/a> Embora o relat\u00f3rio seja significativo, \u00e9 preciso ter em mente que ele n\u00e3o tem for\u00e7a de lei. \u201cEm primeiro lugar, \u00e9 importante observar que, embora o relat\u00f3rio sobre as Doen\u00e7as N\u00e3o Transmiss\u00edveis seja um documento influente, ele n\u00e3o constitui legisla\u00e7\u00e3o e, como tal, n\u00e3o tem consequ\u00eancias diretas para a legisla\u00e7\u00e3o da UE. Isso significa que a ado\u00e7\u00e3o do relat\u00f3rio n\u00e3o se traduz automaticamente em mudan\u00e7as na lei. No entanto, suas implica\u00e7\u00f5es n\u00e3o devem ser subestimadas.\u201d<\/p>\n<p>Leia o texto completo <a href=\"https:\/\/www.vapingpost.com\/2024\/01\/05\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\/\" target=\"_blank\" rel=\"noopener\">aqui.<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>A Non-Communicable Diseases report by the EU&#8217;s Subcommittee on Public Health has officially recognized the effectivity of vaping as a smoking cessation tool. The European Parliament has officially recognized the substantial role of vaping in smoking cessation during a full assembly, following the endorsement of the products by the EU\u2019s Subcommittee on Public Health (SANT) [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6394,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-5333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wva-in-the-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The European Parliament Has Officially Recognized Vaping as a Smoking Cessation Tool - World Vapers&#039; Alliance<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/worldvapersalliance.com\/pt\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The European Parliament Has Officially Recognized Vaping as a Smoking Cessation Tool - World Vapers&#039; Alliance\" \/>\n<meta property=\"og:description\" content=\"A Non-Communicable Diseases report by the EU&#8217;s Subcommittee on Public Health has officially recognized the effectivity of vaping as a smoking cessation tool. The European Parliament has officially recognized the substantial role of vaping in smoking cessation during a full assembly, following the endorsement of the products by the EU\u2019s Subcommittee on Public Health (SANT) [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/worldvapersalliance.com\/pt\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\/\" \/>\n<meta property=\"og:site_name\" content=\"World Vapers&#039; Alliance\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-05T11:18:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-22T11:24:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2022\/08\/vaping-post.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2081\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"World Vapers&#039; Alliance\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"World Vapers&#039; Alliance\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\\\/\"},\"author\":{\"name\":\"World Vapers' Alliance\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#\\\/schema\\\/person\\\/18484a6f20bcc6f70a2419c8babe017d\"},\"headline\":\"The European Parliament Has Officially Recognized Vaping as a Smoking Cessa &hellip;\",\"datePublished\":\"2024-01-05T11:18:29+00:00\",\"dateModified\":\"2024-01-22T11:24:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\\\/\"},\"wordCount\":322,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WVA-in-the-news.png\",\"articleSection\":[\"WVA in the News\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/worldvapersalliance.com\\\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\\\/\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\\\/\",\"name\":\"The European Parliament Has Officially Recognized Vaping as a Smoking Cessation Tool - World Vapers&#039; Alliance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WVA-in-the-news.png\",\"datePublished\":\"2024-01-05T11:18:29+00:00\",\"dateModified\":\"2024-01-22T11:24:52+00:00\",\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/worldvapersalliance.com\\\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\\\/#primaryimage\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WVA-in-the-news.png\",\"contentUrl\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WVA-in-the-news.png\",\"width\":1264,\"height\":848},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#website\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/\",\"name\":\"World Vapers&#039; Alliance\",\"description\":\"The largest community of vapers\",\"publisher\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/worldvapersalliance.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#organization\",\"name\":\"World Vapers&#039; Alliance\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WVA_RB_Fist_G.png\",\"contentUrl\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WVA_RB_Fist_G.png\",\"width\":985,\"height\":1177,\"caption\":\"World Vapers&#039; Alliance\"},\"image\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#\\\/schema\\\/person\\\/18484a6f20bcc6f70a2419c8babe017d\",\"name\":\"World Vapers' Alliance\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g\",\"caption\":\"World Vapers' Alliance\"},\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/pt\\\/author\\\/wva\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O Parlamento Europeu reconheceu oficialmente o vaping como uma ferramenta para deixar de fumar - Alian\u00e7a Mundial de Vapers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/worldvapersalliance.com\/pt\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\/","og_locale":"pt_PT","og_type":"article","og_title":"The European Parliament Has Officially Recognized Vaping as a Smoking Cessation Tool - World Vapers&#039; Alliance","og_description":"A Non-Communicable Diseases report by the EU&#8217;s Subcommittee on Public Health has officially recognized the effectivity of vaping as a smoking cessation tool. The European Parliament has officially recognized the substantial role of vaping in smoking cessation during a full assembly, following the endorsement of the products by the EU\u2019s Subcommittee on Public Health (SANT) [&hellip;]","og_url":"https:\/\/worldvapersalliance.com\/pt\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\/","og_site_name":"World Vapers&#039; Alliance","article_published_time":"2024-01-05T11:18:29+00:00","article_modified_time":"2024-01-22T11:24:52+00:00","og_image":[{"width":2081,"height":1920,"url":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2022\/08\/vaping-post.png","type":"image\/png"}],"author":"World Vapers' Alliance","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"World Vapers' Alliance","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/worldvapersalliance.com\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\/#article","isPartOf":{"@id":"https:\/\/worldvapersalliance.com\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\/"},"author":{"name":"World Vapers' Alliance","@id":"https:\/\/worldvapersalliance.com\/#\/schema\/person\/18484a6f20bcc6f70a2419c8babe017d"},"headline":"The European Parliament Has Officially Recognized Vaping as a Smoking Cessa &hellip;","datePublished":"2024-01-05T11:18:29+00:00","dateModified":"2024-01-22T11:24:52+00:00","mainEntityOfPage":{"@id":"https:\/\/worldvapersalliance.com\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\/"},"wordCount":322,"commentCount":0,"publisher":{"@id":"https:\/\/worldvapersalliance.com\/#organization"},"image":{"@id":"https:\/\/worldvapersalliance.com\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\/#primaryimage"},"thumbnailUrl":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2025\/08\/WVA-in-the-news.png","articleSection":["WVA in the News"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/worldvapersalliance.com\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/worldvapersalliance.com\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\/","url":"https:\/\/worldvapersalliance.com\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\/","name":"O Parlamento Europeu reconheceu oficialmente o vaping como uma ferramenta para deixar de fumar - Alian\u00e7a Mundial de Vapers","isPartOf":{"@id":"https:\/\/worldvapersalliance.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/worldvapersalliance.com\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\/#primaryimage"},"image":{"@id":"https:\/\/worldvapersalliance.com\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\/#primaryimage"},"thumbnailUrl":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2025\/08\/WVA-in-the-news.png","datePublished":"2024-01-05T11:18:29+00:00","dateModified":"2024-01-22T11:24:52+00:00","inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/worldvapersalliance.com\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/worldvapersalliance.com\/the-european-parliament-has-officially-recognized-vaping-as-a-smoking-cessation-tool\/#primaryimage","url":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2025\/08\/WVA-in-the-news.png","contentUrl":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2025\/08\/WVA-in-the-news.png","width":1264,"height":848},{"@type":"WebSite","@id":"https:\/\/worldvapersalliance.com\/#website","url":"https:\/\/worldvapersalliance.com\/","name":"Alian\u00e7a Mundial de Vapers","description":"A maior comunidade de vapers","publisher":{"@id":"https:\/\/worldvapersalliance.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/worldvapersalliance.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/worldvapersalliance.com\/#organization","name":"Alian\u00e7a Mundial de Vapers","url":"https:\/\/worldvapersalliance.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/worldvapersalliance.com\/#\/schema\/logo\/image\/","url":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2022\/01\/WVA_RB_Fist_G.png","contentUrl":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2022\/01\/WVA_RB_Fist_G.png","width":985,"height":1177,"caption":"World Vapers&#039; Alliance"},"image":{"@id":"https:\/\/worldvapersalliance.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/worldvapersalliance.com\/#\/schema\/person\/18484a6f20bcc6f70a2419c8babe017d","name":"Alian\u00e7a Mundial de Vapers","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g","caption":"World Vapers' Alliance"},"url":"https:\/\/worldvapersalliance.com\/pt\/author\/wva\/"}]}},"_links":{"self":[{"href":"https:\/\/worldvapersalliance.com\/pt\/wp-json\/wp\/v2\/posts\/5333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/worldvapersalliance.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/worldvapersalliance.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/worldvapersalliance.com\/pt\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/worldvapersalliance.com\/pt\/wp-json\/wp\/v2\/comments?post=5333"}],"version-history":[{"count":0,"href":"https:\/\/worldvapersalliance.com\/pt\/wp-json\/wp\/v2\/posts\/5333\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/worldvapersalliance.com\/pt\/wp-json\/wp\/v2\/media\/6394"}],"wp:attachment":[{"href":"https:\/\/worldvapersalliance.com\/pt\/wp-json\/wp\/v2\/media?parent=5333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/worldvapersalliance.com\/pt\/wp-json\/wp\/v2\/categories?post=5333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/worldvapersalliance.com\/pt\/wp-json\/wp\/v2\/tags?post=5333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}