{"id":4981,"date":"2023-10-27T09:40:03","date_gmt":"2023-10-27T13:40:03","guid":{"rendered":"https:\/\/worldvapersalliance.com\/?p=4981"},"modified":"2023-10-30T09:44:54","modified_gmt":"2023-10-30T13:44:54","slug":"the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking","status":"publish","type":"post","link":"https:\/\/worldvapersalliance.com\/it\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\/","title":{"rendered":"L\u2019UE ha perso l\u2019occasione di guidare la guerra al fumo"},"content":{"rendered":"<p>L&#039;Organizzazione Mondiale della Sanit\u00e0 (OMS) segnala ogni anno la cifra sbalorditiva di otto milioni di decessi dovuti al fumo. Seguendo l&#039;esempio dell&#039;OMS, l&#039;UE ha posto come priorit\u00e0 la lotta al fumo e alle malattie indotte dal fumo. Tuttavia, nonostante la sua posizione contraria alle sigarette, le azioni dell&#039;UE sollevano serie preoccupazioni. Un approccio distaccato alla riduzione del danno e l&#039;incapacit\u00e0 di riconoscere i fallimenti evidenti caratterizzano l&#039;attuale posizione dell&#039;istituzione sul fumo.<\/p>\n<p>Negli ultimi anni, l&#039;UE ha cercato di combattere il tabacco attraverso il Piano UE per la Lotta contro il Cancro, poi con i tentativi di revisione della Direttiva sui Prodotti Tabacchi e regolamentando le accise sul tabacco attraverso la Direttiva sulle Accise, che alla fine non ha mai visto la luce. Eppure, ogni volta l&#039;UE sembra ancora faticare a comprendere il vero nemico.<\/p>\n<p>Mentre l&#039;UE adotta la sua posizione per la 10a Conferenza delle Parti (COP10) della Convenzione quadro sulle sigarette elettroniche (FCTC) dell&#039;OMS, che si terr\u00e0 a Panama il prossimo novembre, la riduzione del danno \u00e8 messa a rischio ancora di pi\u00f9. A seguito della lotta dell&#039;OMS contro il tabacco, l&#039;UE accoglie con favore una regolamentazione ancora pi\u00f9 severa delle sigarette elettroniche e sostiene prodotti come aromi e prodotti monouso. Ci\u00f2 solleva una domanda:,<strong> <em>Se l&#039;UE \u00e8 determinata a combattere il fumo, perch\u00e9 allora eliminare la riduzione del danno?<\/em><\/strong><\/p>\n<p>La FCTC \u00e8 il pilastro del controllo globale del tabacco. Adottato nel 2003 ed entrato in vigore nel 2005, questo trattato mira a offrire una risposta collettiva all&#039;epidemia di fumo, aspirando a ridurre sia la domanda che l&#039;offerta di prodotti del tabacco e della nicotina. Alla luce di quanto sopra, cosa offre la COP10? Uno sguardo preoccupante ai recenti <a href=\"https:\/\/www.who.int\/groups\/who-study-group-on-tobacco-product-regulation\">Rapporti TobReg<\/a> rivela raccomandazioni destinate a compromettere ulteriormente gli sforzi globali per smettere di fumare. Dall&#039;equiparare i prodotti a base di nicotina pi\u00f9 sicuri alle sigarette tradizionali al divieto di aromi per lo svapo e all&#039;aumento delle tasse sulle alternative al fumo, le misure proposte sembrano, nella migliore delle ipotesi, controintuitive.<\/p>\n<p>L&#039;adozione di tali misure rallenter\u00e0 senza dubbio, se non addirittura invertir\u00e0, i progressi compiuti dalle nazioni che hanno adottato un approccio progressista alle alternative alla nicotina. Ad esempio, gli aromi nei prodotti per lo svapo aumentano la probabilit\u00e0 di smettere di fumare entro un <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/32501490\/\">notevole 230%<\/a>. Limitare o vietare queste misure spinger\u00e0 senza dubbio gli individui a tornare al fumo tradizionale o al rischioso mercato nero. Nel caso degli sforzi dell&#039;UE per limitare il fumo, l&#039;UE non potrebbe guardare oltre la propria Svezia, che non solo \u00e8 sulla strada per diventare <strong>il primo paese al mondo senza fumo<\/strong> Grazie al suo innegabile sostegno allo svapo, allo snus e, pi\u00f9 di recente, alle bustine di nicotina, la Svezia continua a sostenere la sua lotta contro il fumo aumentando le tasse sulle sigarette e riducendo quelle sullo snus entro il 2014.<\/p>\n<p>In effetti, la Svezia <a href=\"https:\/\/www.brusselsreport.eu\/2023\/05\/31\/the-eu-should-rethink-its-anti-smoking-policies-adopting-the-swedish-model-instead\/\">successo<\/a> pu\u00f2 essere spiegato in due parole: riduzione del danno. La Svezia ha adottato un approccio lungimirante alla riduzione del fumo, integrando strategie di riduzione del danno, come il supporto ai prodotti per la somministrazione di nicotina, come lo svapo o le bustine di nicotina, e l&#039;applicazione di strategie basate sul rischio. <a href=\"https:\/\/www.regeringen.se\/pressmeddelanden\/2023\/09\/sankt-skatt-pa-snus\/\">tassazione<\/a> su prodotti come lo snus.<\/p>\n<p>Purtroppo, l&#039;UE e, per la precisione, l&#039;OMS sembrano ignorare questo risultato, forse a causa dei metodi non convenzionali impiegati dalla Svezia. Invece di misure restrittive come quelle promosse dall&#039;OMS, la Svezia ha adottato normative basate sul rischio e favorevoli al consumatore, anzich\u00e9 limitarsi a divieti. In un sconcertante contrasto, l&#039;OMS loda <a href=\"https:\/\/www.who.int\/turkmenistan\/news\/item\/12-07-2023-turkmen-youth-advocate-for-tobacco-free-country\">Turkmenistan<\/a> \u2014 nonostante la sua notoria reputazione di una delle dittature pi\u00f9 oppressive del mondo \u2014 di detenere &quot;una posizione di leadership nel controllo e nella prevenzione del tabacco&quot;. Questo paradosso non \u00e8 solo sorprendente; rasenta il disumano e il condiscendente. Ci si aspetterebbe un&#039;eco di protesta contro posizioni cos\u00ec contraddittorie da parte degli altri Stati membri dell&#039;OMS e dei media. Ma la risposta? Un silenzio inquietante. \u00c8 angosciante che la comunit\u00e0 internazionale sembri imperturbabile di fronte agli evidenti passi falsi dell&#039;OMS, soprattutto quando l&#039;organizzazione chiude un occhio sui trionfi di nazioni progressiste come la Svezia.<\/p>\n<p>\u00c8 giunto il momento che l&#039;UE prenda esempio dal successo ottenuto in Svezia. La Svezia ci ha dimostrato che per combattere il fumo non \u00e8 necessario regolamentare eccessivamente, ma solo in modo pi\u00f9 intelligente. Quando si \u00e8 diffusa la notizia dello spettacolare successo svedese, l&#039;UE avrebbe potuto assumere la leadership e collaborare con gli Stati membri per elaborare approcci intelligenti basati sul rischio per ciascun paese. Invece? La Commissione parteciper\u00e0 alla Conferenza delle Parti senza innovazione, n\u00e9 leadership, n\u00e9 successo.<\/p>\n<p><strong>Perseverare in una guerra contro alternative pi\u00f9 sicure alla nicotina non \u00e8 solo dannoso, \u00e8 fatale. La riduzione del danno non \u00e8 un semplice slogan; \u00e8 una strategia salvavita che merita l&#039;approvazione globale. La posta in gioco non \u00e8 mai stata cos\u00ec alta: la vita di milioni di persone \u00e8 in gioco.<\/strong><\/p>\n<p>Originariamente pubblicato <a href=\"https:\/\/www.brusselsreport.eu\/2023\/10\/27\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\/\" target=\"_blank\" rel=\"noopener\">Qui<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>The World Health Organization (WHO) reports a staggering eight million deaths due to smoking annually. Following the WHO\u2019s lead, the EU has set as one its priorities to fighting smoking and smoking-induced diseases. Yet, despite its stance against cigarettes, the EU\u2019s actions raise serious concerns. A detached approach to harm reduction and an inability to [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6394,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-4981","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wva-in-the-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The EU has missed the opportunity to lead the war on smoking - World Vapers&#039; Alliance<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/worldvapersalliance.com\/it\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The EU has missed the opportunity to lead the war on smoking - World Vapers&#039; Alliance\" \/>\n<meta property=\"og:description\" content=\"The World Health Organization (WHO) reports a staggering eight million deaths due to smoking annually. Following the WHO\u2019s lead, the EU has set as one its priorities to fighting smoking and smoking-induced diseases. Yet, despite its stance against cigarettes, the EU\u2019s actions raise serious concerns. A detached approach to harm reduction and an inability to [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/worldvapersalliance.com\/it\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\/\" \/>\n<meta property=\"og:site_name\" content=\"World Vapers&#039; Alliance\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-27T13:40:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-30T13:44:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2022\/10\/Brussels-Report.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2081\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"World Vapers&#039; Alliance\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"World Vapers&#039; Alliance\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\\\/\"},\"author\":{\"name\":\"World Vapers' Alliance\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#\\\/schema\\\/person\\\/18484a6f20bcc6f70a2419c8babe017d\"},\"headline\":\"The EU has missed the opportunity to lead the war on smoking\",\"datePublished\":\"2023-10-27T13:40:03+00:00\",\"dateModified\":\"2023-10-30T13:44:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\\\/\"},\"wordCount\":743,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WVA-in-the-news.png\",\"articleSection\":[\"WVA in the News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/worldvapersalliance.com\\\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\\\/\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\\\/\",\"name\":\"The EU has missed the opportunity to lead the war on smoking - World Vapers&#039; Alliance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WVA-in-the-news.png\",\"datePublished\":\"2023-10-27T13:40:03+00:00\",\"dateModified\":\"2023-10-30T13:44:54+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/worldvapersalliance.com\\\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\\\/#primaryimage\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WVA-in-the-news.png\",\"contentUrl\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WVA-in-the-news.png\",\"width\":1264,\"height\":848},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#website\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/\",\"name\":\"World Vapers&#039; Alliance\",\"description\":\"The largest community of vapers\",\"publisher\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/worldvapersalliance.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#organization\",\"name\":\"World Vapers&#039; Alliance\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WVA_RB_Fist_G.png\",\"contentUrl\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WVA_RB_Fist_G.png\",\"width\":985,\"height\":1177,\"caption\":\"World Vapers&#039; Alliance\"},\"image\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#\\\/schema\\\/person\\\/18484a6f20bcc6f70a2419c8babe017d\",\"name\":\"World Vapers' Alliance\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g\",\"caption\":\"World Vapers' Alliance\"},\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/it\\\/author\\\/wva\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L&#039;UE ha perso l&#039;occasione di guidare la guerra al fumo - World Vapers&#039; Alliance","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/worldvapersalliance.com\/it\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\/","og_locale":"it_IT","og_type":"article","og_title":"The EU has missed the opportunity to lead the war on smoking - World Vapers&#039; Alliance","og_description":"The World Health Organization (WHO) reports a staggering eight million deaths due to smoking annually. Following the WHO\u2019s lead, the EU has set as one its priorities to fighting smoking and smoking-induced diseases. Yet, despite its stance against cigarettes, the EU\u2019s actions raise serious concerns. A detached approach to harm reduction and an inability to [&hellip;]","og_url":"https:\/\/worldvapersalliance.com\/it\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\/","og_site_name":"World Vapers&#039; Alliance","article_published_time":"2023-10-27T13:40:03+00:00","article_modified_time":"2023-10-30T13:44:54+00:00","og_image":[{"width":2081,"height":1920,"url":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2022\/10\/Brussels-Report.png","type":"image\/png"}],"author":"World Vapers' Alliance","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"World Vapers' Alliance","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/worldvapersalliance.com\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\/#article","isPartOf":{"@id":"https:\/\/worldvapersalliance.com\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\/"},"author":{"name":"World Vapers' Alliance","@id":"https:\/\/worldvapersalliance.com\/#\/schema\/person\/18484a6f20bcc6f70a2419c8babe017d"},"headline":"The EU has missed the opportunity to lead the war on smoking","datePublished":"2023-10-27T13:40:03+00:00","dateModified":"2023-10-30T13:44:54+00:00","mainEntityOfPage":{"@id":"https:\/\/worldvapersalliance.com\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\/"},"wordCount":743,"commentCount":0,"publisher":{"@id":"https:\/\/worldvapersalliance.com\/#organization"},"image":{"@id":"https:\/\/worldvapersalliance.com\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\/#primaryimage"},"thumbnailUrl":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2025\/08\/WVA-in-the-news.png","articleSection":["WVA in the News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/worldvapersalliance.com\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/worldvapersalliance.com\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\/","url":"https:\/\/worldvapersalliance.com\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\/","name":"L&#039;UE ha perso l&#039;occasione di guidare la guerra al fumo - World Vapers&#039; Alliance","isPartOf":{"@id":"https:\/\/worldvapersalliance.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/worldvapersalliance.com\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\/#primaryimage"},"image":{"@id":"https:\/\/worldvapersalliance.com\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\/#primaryimage"},"thumbnailUrl":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2025\/08\/WVA-in-the-news.png","datePublished":"2023-10-27T13:40:03+00:00","dateModified":"2023-10-30T13:44:54+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/worldvapersalliance.com\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/worldvapersalliance.com\/the-eu-has-missed-the-opportunity-to-lead-the-war-on-smoking\/#primaryimage","url":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2025\/08\/WVA-in-the-news.png","contentUrl":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2025\/08\/WVA-in-the-news.png","width":1264,"height":848},{"@type":"WebSite","@id":"https:\/\/worldvapersalliance.com\/#website","url":"https:\/\/worldvapersalliance.com\/","name":"Alleanza mondiale dei vapers","description":"La pi\u00f9 grande comunit\u00e0 di vapers","publisher":{"@id":"https:\/\/worldvapersalliance.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/worldvapersalliance.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/worldvapersalliance.com\/#organization","name":"Alleanza mondiale dei vapers","url":"https:\/\/worldvapersalliance.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/worldvapersalliance.com\/#\/schema\/logo\/image\/","url":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2022\/01\/WVA_RB_Fist_G.png","contentUrl":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2022\/01\/WVA_RB_Fist_G.png","width":985,"height":1177,"caption":"World Vapers&#039; Alliance"},"image":{"@id":"https:\/\/worldvapersalliance.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/worldvapersalliance.com\/#\/schema\/person\/18484a6f20bcc6f70a2419c8babe017d","name":"Alleanza mondiale dei vapers","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g","caption":"World Vapers' Alliance"},"url":"https:\/\/worldvapersalliance.com\/it\/author\/wva\/"}]}},"_links":{"self":[{"href":"https:\/\/worldvapersalliance.com\/it\/wp-json\/wp\/v2\/posts\/4981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/worldvapersalliance.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/worldvapersalliance.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/worldvapersalliance.com\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/worldvapersalliance.com\/it\/wp-json\/wp\/v2\/comments?post=4981"}],"version-history":[{"count":0,"href":"https:\/\/worldvapersalliance.com\/it\/wp-json\/wp\/v2\/posts\/4981\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/worldvapersalliance.com\/it\/wp-json\/wp\/v2\/media\/6394"}],"wp:attachment":[{"href":"https:\/\/worldvapersalliance.com\/it\/wp-json\/wp\/v2\/media?parent=4981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/worldvapersalliance.com\/it\/wp-json\/wp\/v2\/categories?post=4981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/worldvapersalliance.com\/it\/wp-json\/wp\/v2\/tags?post=4981"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}