{"id":5291,"date":"2024-01-02T08:44:18","date_gmt":"2024-01-02T13:44:18","guid":{"rendered":"https:\/\/worldvapersalliance.com\/?p=5291"},"modified":"2024-01-03T08:45:43","modified_gmt":"2024-01-03T13:45:43","slug":"piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico","status":"publish","type":"post","link":"https:\/\/worldvapersalliance.com\/es\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\/","title":{"rendered":"Piden a Milei la libre comercializaci\u00f3n del cigarrillo electr\u00f3nico"},"content":{"rendered":"<h4 class=\"subtitle\">La Asovape Argentina en una carta abierta se solicita que se derogue la disposici\u00f3n administrativa de la ANMAT que as\u00ed lo prohibe<\/h4>\n<p>La asociaci\u00f3n argentina de vapeadores Asovape Argentina y la World Vapers&#039; Alliance han enviado una al presidente de la Naci\u00f3n Argentina, Javier Milei, en la que piden la derogaci\u00f3n de la disposici\u00f3n administrativa de la ANMAT que proh\u00edbe la comercializaci\u00f3n del cigarrillo electr\u00f3nico.<\/p>\n<p>La disposici\u00f3n 3226\/2011 de la Administraci\u00f3n Nacional de Medicamentos, Alimentos y Tecnolog\u00eda M\u00e9dica (ANMAT) prohibi\u00f3 el 6 de mayo de 2011 la importaci\u00f3n, distribuci\u00f3n, comercializaci\u00f3n, publicidad y promoci\u00f3n de los cigarrillos electr\u00f3nicos tras concluir que la nicotina era una droga altamente t\u00f3xica. y que no exist\u00eda evidencia cient\u00edfica suficiente para afirmar que los cigarrillos electr\u00f3nicos eran menos da\u00f1inos que el tabaco y que serv\u00edan como herramienta para dejar de fumar.<\/p>\n<p>Las asociaciones firmantes explican en la carta que numerosos estudios realizados desde la entrada en vigor de la prohibici\u00f3n han demostrado el perfil de riesgo significativamente inferior y la utilidad para dejar de fumar de estos dispositivos, as\u00ed como el bajo riesgo para la salud de la nicotina. Tambi\u00e9n argumentan que la prohibici\u00f3n es incompatible con el respeto a la libertad individual de los adultos argentinos y los derechos al libre desarrollo de la personalidad, la informaci\u00f3n y la salud de usuarios y fumadores.<\/p>\n<p>Lea el texto completo <a href=\"https:\/\/www.cadenanueve.com\/2024\/01\/02\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\/\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>La Asovape Argentina en una carta abierta se solicita que se derogue la disposici\u00f3n administrativa de la ANMAT que as\u00ed lo prohibe La asociaci\u00f3n argentina de vapeadores Asovape Argentina y la World Vapers\u2019 Alliance han enviado una \u00a0 al presidente de la Naci\u00f3n Argentina, Javier Milei, en la que piden la derogaci\u00f3n de la disposici\u00f3n [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6394,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-5291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wva-in-the-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Piden a Milei la libre comercializaci\u00f3n del cigarrillo electr\u00f3nico - World Vapers&#039; Alliance<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/worldvapersalliance.com\/es\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Piden a Milei la libre comercializaci\u00f3n del cigarrillo electr\u00f3nico - World Vapers&#039; Alliance\" \/>\n<meta property=\"og:description\" content=\"La Asovape Argentina en una carta abierta se solicita que se derogue la disposici\u00f3n administrativa de la ANMAT que as\u00ed lo prohibe La asociaci\u00f3n argentina de vapeadores Asovape Argentina y la World Vapers\u2019 Alliance han enviado una \u00a0 al presidente de la Naci\u00f3n Argentina, Javier Milei, en la que piden la derogaci\u00f3n de la disposici\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/worldvapersalliance.com\/es\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\/\" \/>\n<meta property=\"og:site_name\" content=\"World Vapers&#039; Alliance\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-02T13:44:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-03T13:45:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2024\/01\/Cadena-Nueve.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2081\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"World Vapers&#039; Alliance\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"World Vapers&#039; Alliance\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\\\/\"},\"author\":{\"name\":\"World Vapers' Alliance\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#\\\/schema\\\/person\\\/18484a6f20bcc6f70a2419c8babe017d\"},\"headline\":\"Piden a Milei la libre comercializaci\u00f3n del cigarrillo electr\u00f3nico\",\"datePublished\":\"2024-01-02T13:44:18+00:00\",\"dateModified\":\"2024-01-03T13:45:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\\\/\"},\"wordCount\":259,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WVA-in-the-news.png\",\"articleSection\":[\"WVA in the News\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/worldvapersalliance.com\\\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\\\/\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\\\/\",\"name\":\"Piden a Milei la libre comercializaci\u00f3n del cigarrillo electr\u00f3nico - World Vapers&#039; Alliance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WVA-in-the-news.png\",\"datePublished\":\"2024-01-02T13:44:18+00:00\",\"dateModified\":\"2024-01-03T13:45:43+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/worldvapersalliance.com\\\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WVA-in-the-news.png\",\"contentUrl\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WVA-in-the-news.png\",\"width\":1264,\"height\":848},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#website\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/\",\"name\":\"World Vapers&#039; Alliance\",\"description\":\"The largest community of vapers\",\"publisher\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/worldvapersalliance.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#organization\",\"name\":\"World Vapers&#039; Alliance\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WVA_RB_Fist_G.png\",\"contentUrl\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WVA_RB_Fist_G.png\",\"width\":985,\"height\":1177,\"caption\":\"World Vapers&#039; Alliance\"},\"image\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#\\\/schema\\\/person\\\/18484a6f20bcc6f70a2419c8babe017d\",\"name\":\"World Vapers' Alliance\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g\",\"caption\":\"World Vapers' Alliance\"},\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/es\\\/author\\\/wva\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Piden a Milei la libre comercializaci\u00f3n del cigarrillo electr\u00f3nico - World Vapers&#039; Alliance","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/worldvapersalliance.com\/es\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\/","og_locale":"es_ES","og_type":"article","og_title":"Piden a Milei la libre comercializaci\u00f3n del cigarrillo electr\u00f3nico - World Vapers&#039; Alliance","og_description":"La Asovape Argentina en una carta abierta se solicita que se derogue la disposici\u00f3n administrativa de la ANMAT que as\u00ed lo prohibe La asociaci\u00f3n argentina de vapeadores Asovape Argentina y la World Vapers\u2019 Alliance han enviado una \u00a0 al presidente de la Naci\u00f3n Argentina, Javier Milei, en la que piden la derogaci\u00f3n de la disposici\u00f3n [&hellip;]","og_url":"https:\/\/worldvapersalliance.com\/es\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\/","og_site_name":"World Vapers&#039; Alliance","article_published_time":"2024-01-02T13:44:18+00:00","article_modified_time":"2024-01-03T13:45:43+00:00","og_image":[{"width":2081,"height":1920,"url":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2024\/01\/Cadena-Nueve.png","type":"image\/png"}],"author":"World Vapers' Alliance","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"World Vapers' Alliance","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/worldvapersalliance.com\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\/#article","isPartOf":{"@id":"https:\/\/worldvapersalliance.com\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\/"},"author":{"name":"World Vapers' Alliance","@id":"https:\/\/worldvapersalliance.com\/#\/schema\/person\/18484a6f20bcc6f70a2419c8babe017d"},"headline":"Piden a Milei la libre comercializaci\u00f3n del cigarrillo electr\u00f3nico","datePublished":"2024-01-02T13:44:18+00:00","dateModified":"2024-01-03T13:45:43+00:00","mainEntityOfPage":{"@id":"https:\/\/worldvapersalliance.com\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\/"},"wordCount":259,"commentCount":0,"publisher":{"@id":"https:\/\/worldvapersalliance.com\/#organization"},"image":{"@id":"https:\/\/worldvapersalliance.com\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\/#primaryimage"},"thumbnailUrl":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2025\/08\/WVA-in-the-news.png","articleSection":["WVA in the News"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/worldvapersalliance.com\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/worldvapersalliance.com\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\/","url":"https:\/\/worldvapersalliance.com\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\/","name":"Piden a Milei la libre comercializaci\u00f3n del cigarrillo electr\u00f3nico - World Vapers&#039; Alliance","isPartOf":{"@id":"https:\/\/worldvapersalliance.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/worldvapersalliance.com\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\/#primaryimage"},"image":{"@id":"https:\/\/worldvapersalliance.com\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\/#primaryimage"},"thumbnailUrl":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2025\/08\/WVA-in-the-news.png","datePublished":"2024-01-02T13:44:18+00:00","dateModified":"2024-01-03T13:45:43+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/worldvapersalliance.com\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/worldvapersalliance.com\/piden-a-milei-la-libre-comercializacion-del-cigarrillo-electronico\/#primaryimage","url":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2025\/08\/WVA-in-the-news.png","contentUrl":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2025\/08\/WVA-in-the-news.png","width":1264,"height":848},{"@type":"WebSite","@id":"https:\/\/worldvapersalliance.com\/#website","url":"https:\/\/worldvapersalliance.com\/","name":"Alianza Mundial de Vapeadores","description":"La comunidad m\u00e1s grande de vapeadores","publisher":{"@id":"https:\/\/worldvapersalliance.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/worldvapersalliance.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/worldvapersalliance.com\/#organization","name":"Alianza Mundial de Vapeadores","url":"https:\/\/worldvapersalliance.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/worldvapersalliance.com\/#\/schema\/logo\/image\/","url":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2022\/01\/WVA_RB_Fist_G.png","contentUrl":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2022\/01\/WVA_RB_Fist_G.png","width":985,"height":1177,"caption":"World Vapers&#039; Alliance"},"image":{"@id":"https:\/\/worldvapersalliance.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/worldvapersalliance.com\/#\/schema\/person\/18484a6f20bcc6f70a2419c8babe017d","name":"Alianza Mundial de Vapeadores","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g","caption":"World Vapers' Alliance"},"url":"https:\/\/worldvapersalliance.com\/es\/author\/wva\/"}]}},"_links":{"self":[{"href":"https:\/\/worldvapersalliance.com\/es\/wp-json\/wp\/v2\/posts\/5291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/worldvapersalliance.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/worldvapersalliance.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/worldvapersalliance.com\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/worldvapersalliance.com\/es\/wp-json\/wp\/v2\/comments?post=5291"}],"version-history":[{"count":0,"href":"https:\/\/worldvapersalliance.com\/es\/wp-json\/wp\/v2\/posts\/5291\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/worldvapersalliance.com\/es\/wp-json\/wp\/v2\/media\/6394"}],"wp:attachment":[{"href":"https:\/\/worldvapersalliance.com\/es\/wp-json\/wp\/v2\/media?parent=5291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/worldvapersalliance.com\/es\/wp-json\/wp\/v2\/categories?post=5291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/worldvapersalliance.com\/es\/wp-json\/wp\/v2\/tags?post=5291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}