{"id":4942,"date":"2023-10-17T07:43:26","date_gmt":"2023-10-17T11:43:26","guid":{"rendered":"https:\/\/worldvapersalliance.com\/?p=4942"},"modified":"2023-10-24T07:47:41","modified_gmt":"2023-10-24T11:47:41","slug":"la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo","status":"publish","type":"post","link":"https:\/\/worldvapersalliance.com\/da\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\/","title":{"rendered":"La Svezia vuole detassare i prodotti alternative al tabacco combusto per po \u2026"},"content":{"rendered":"<p>La soluzione scandinava per combattere le sigarette tradizionali<\/p>\n<p>Le proposte attuate in Svezia per incentivare il ricorso ai\u00a0<strong>alternativer til tabacco combusto\u00a0<\/strong>si integrano alla perfezione con la consapevolezza del fatto che la sigaretta elettronica possa costituire una preziosa chance nella lotta al fumo di tabacco, i quanto nettamente meno nociva. Il concetto, a ben vedere, \u00e8 molto semplice: minore \u00e8 il danno, pi\u00f9 bassa \u00e8 la pressione fiscale.<\/p>\n<p>Regeringsmeddelelsen<\/p>\n<p>Il governo infatti ha reso noto di avere intenzione di abbassare le tasse che si applicano sui prodotti non da fumo, come per esempio\u00a0<strong>gli e-v\u00e6sker e il tabacco da fiuto<\/strong>, mentre incrementer\u00e0 le tasse sui sigari e sulle sigarette. Se questo stesso provvedimento venisse adottato anche nel nostro Paese, i prodotti come i\u00a0<a href=\"https:\/\/www.svapoebasta.com\/219-vaporart-liquidi-pronti\">pronti v\u00e6ske Vaporart<\/a>\u00a0costerebbero meno, cos\u00ec come le sigarette usa e getta e altri accessori. I s\u00e6rdeleshed, la volont\u00e0 della Svezia \u00e8 quella di\u00a0<strong>r\u00f8vede p\u00e5l\u00e6gget<\/strong>\u00a0sullo snus, vale a dire i sacchetti di tabacco destinati a un uso orale, di ben il 20%; al tempo stesso, verrebbe incrementata del 9% l&#039;imposta sui prodotti del tabacco con combustione. Sul sito web istituzionale del governo \u00e8 stata pubblicata una not con la quale il governo ha fatto riferimento alla volont\u00e0 di ridurre di 3 corone svedesi, pari pi\u00f9 o meno a 25 centesimi di euro, il costo di\u00a0<strong>en snuskonfektion<\/strong>. I base alla normativa svedese, i prodotti del tabacco non da fumo sono caratterizzati da una pressione fiscale pi\u00f9 bassa rispetto a quella che colpisce i sigari e le sigarette tradizionali, dal momento che essi vengono considerati meno nocivi dal punto di vista della\u00a0<strong>salut<\/strong>.<\/p>\n<p>Der er en vigtig politisk beslutning<\/p>\n<p>Jeg er sikker p\u00e5, at du er sikker p\u00e5, at Svezia er\u00a0<strong>politiske beslutninger<\/strong>\u00a0di importanza pi\u00f9 che rilevante, attraverso la quale ha tra l&#039;altro rafforzato il proprio ruolo di leader a livello continentale per ci\u00f2 che concerne la riduzione del danno. \u00c8 stato, infatti, stabilito uno standard che potrebbe fungere da esempio per tutta l&#039;\u2019<a href=\"https:\/\/european-union.europa.eu\/\">Den Europ\u00e6iske Union<\/a>, la quale potrebbe avere a disposizione in questo modo una proposta virtuosa a beneficio di tutta la salute pubblica. \u00c8 chiaro, infatti, che una regolamentazione e una tassazione fondate sull&#039;indice di rischio potrebbero costituire un incentivo per i fumatori a utilizzare prodotti meno nocivi, a cominciare dalla\u00a0<strong>elektronisk cigaret<\/strong>. La decisione ha ricevuto il plauso di coloro che sostengono la riduzione del danno. \u00c8 il caso, per esempio, del direttore della World Vapers&#039; Alliance, Michael Landl, secondo il quale \u00e8 giunto il momento che l&#039;UE prenda esempio dalla Svezia. Se lo\u00a0<strong>snus<\/strong>\u00a0venisse legalizzato in tutto il Vecchio Continente, con la contemporanea applicazione di una tassazione mirata e una normativa fondata sul rischio, si avrebbe a che fare con un punto di svolta per tutta la politica di sanit\u00e0 pubblica.<\/p>\n<p>L\u00e6s hele teksten <a href=\"https:\/\/www.lagazzettadisansevero.it\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\/\" target=\"_blank\" rel=\"noopener\">her<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>La soluzione scandinava per combattere le sigarette tradizionali Le proposte attuate in Svezia per incentivare il ricorso ai\u00a0prodotti alternativi al tabacco combusto\u00a0si integrano alla perfezione con la consapevolezza del fatto che la sigaretta elettronica possa costituire una preziosa chance nella lotta al fumo di tabacco, in quanto nettamente meno nociva. Il concetto, a ben vedere, [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6394,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-4942","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wva-in-the-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Svezia vuole detassare i prodotti alternativi al tabacco combusto per potenziare la lotta al fumo - World Vapers&#039; Alliance<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/worldvapersalliance.com\/da\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\/\" \/>\n<meta property=\"og:locale\" content=\"da_DK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Svezia vuole detassare i prodotti alternativi al tabacco combusto per potenziare la lotta al fumo - World Vapers&#039; Alliance\" \/>\n<meta property=\"og:description\" content=\"La soluzione scandinava per combattere le sigarette tradizionali Le proposte attuate in Svezia per incentivare il ricorso ai\u00a0prodotti alternativi al tabacco combusto\u00a0si integrano alla perfezione con la consapevolezza del fatto che la sigaretta elettronica possa costituire una preziosa chance nella lotta al fumo di tabacco, in quanto nettamente meno nociva. Il concetto, a ben vedere, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/worldvapersalliance.com\/da\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\/\" \/>\n<meta property=\"og:site_name\" content=\"World Vapers&#039; Alliance\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-17T11:43:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-24T11:47:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2023\/10\/La-gazzetta.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2081\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"World Vapers&#039; Alliance\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Skrevet af\" \/>\n\t<meta name=\"twitter:data1\" content=\"World Vapers&#039; Alliance\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimeret l\u00e6setid\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutter\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\\\/\"},\"author\":{\"name\":\"World Vapers' Alliance\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#\\\/schema\\\/person\\\/18484a6f20bcc6f70a2419c8babe017d\"},\"headline\":\"La Svezia vuole detassare i prodotti alternativi al tabacco combusto per po &hellip;\",\"datePublished\":\"2023-10-17T11:43:26+00:00\",\"dateModified\":\"2023-10-24T11:47:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\\\/\"},\"wordCount\":477,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WVA-in-the-news.png\",\"articleSection\":[\"WVA in the News\"],\"inLanguage\":\"da-DK\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/worldvapersalliance.com\\\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\\\/\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\\\/\",\"name\":\"La Svezia vuole detassare i prodotti alternativi al tabacco combusto per potenziare la lotta al fumo - World Vapers&#039; Alliance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WVA-in-the-news.png\",\"datePublished\":\"2023-10-17T11:43:26+00:00\",\"dateModified\":\"2023-10-24T11:47:41+00:00\",\"inLanguage\":\"da-DK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/worldvapersalliance.com\\\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"da-DK\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WVA-in-the-news.png\",\"contentUrl\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/WVA-in-the-news.png\",\"width\":1264,\"height\":848},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#website\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/\",\"name\":\"World Vapers&#039; Alliance\",\"description\":\"The largest community of vapers\",\"publisher\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/worldvapersalliance.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"da-DK\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#organization\",\"name\":\"World Vapers&#039; Alliance\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"da-DK\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WVA_RB_Fist_G.png\",\"contentUrl\":\"https:\\\/\\\/worldvapersalliance.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WVA_RB_Fist_G.png\",\"width\":985,\"height\":1177,\"caption\":\"World Vapers&#039; Alliance\"},\"image\":{\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/worldvapersalliance.com\\\/#\\\/schema\\\/person\\\/18484a6f20bcc6f70a2419c8babe017d\",\"name\":\"World Vapers' Alliance\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"da-DK\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g\",\"caption\":\"World Vapers' Alliance\"},\"url\":\"https:\\\/\\\/worldvapersalliance.com\\\/da\\\/author\\\/wva\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Svezia vuole detassare i prodotti alternative al tabacco combusto per potenziare la lotta al fumo - World Vapers&#039; Alliance","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/worldvapersalliance.com\/da\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\/","og_locale":"da_DK","og_type":"article","og_title":"La Svezia vuole detassare i prodotti alternativi al tabacco combusto per potenziare la lotta al fumo - World Vapers&#039; Alliance","og_description":"La soluzione scandinava per combattere le sigarette tradizionali Le proposte attuate in Svezia per incentivare il ricorso ai\u00a0prodotti alternativi al tabacco combusto\u00a0si integrano alla perfezione con la consapevolezza del fatto che la sigaretta elettronica possa costituire una preziosa chance nella lotta al fumo di tabacco, in quanto nettamente meno nociva. Il concetto, a ben vedere, [&hellip;]","og_url":"https:\/\/worldvapersalliance.com\/da\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\/","og_site_name":"World Vapers&#039; Alliance","article_published_time":"2023-10-17T11:43:26+00:00","article_modified_time":"2023-10-24T11:47:41+00:00","og_image":[{"width":2081,"height":1920,"url":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2023\/10\/La-gazzetta.png","type":"image\/png"}],"author":"World Vapers' Alliance","twitter_card":"summary_large_image","twitter_misc":{"Skrevet af":"World Vapers' Alliance","Estimeret l\u00e6setid":"3 minutter"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/worldvapersalliance.com\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\/#article","isPartOf":{"@id":"https:\/\/worldvapersalliance.com\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\/"},"author":{"name":"World Vapers' Alliance","@id":"https:\/\/worldvapersalliance.com\/#\/schema\/person\/18484a6f20bcc6f70a2419c8babe017d"},"headline":"La Svezia vuole detassare i prodotti alternativi al tabacco combusto per po &hellip;","datePublished":"2023-10-17T11:43:26+00:00","dateModified":"2023-10-24T11:47:41+00:00","mainEntityOfPage":{"@id":"https:\/\/worldvapersalliance.com\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\/"},"wordCount":477,"commentCount":0,"publisher":{"@id":"https:\/\/worldvapersalliance.com\/#organization"},"image":{"@id":"https:\/\/worldvapersalliance.com\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\/#primaryimage"},"thumbnailUrl":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2025\/08\/WVA-in-the-news.png","articleSection":["WVA in the News"],"inLanguage":"da-DK","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/worldvapersalliance.com\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/worldvapersalliance.com\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\/","url":"https:\/\/worldvapersalliance.com\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\/","name":"La Svezia vuole detassare i prodotti alternative al tabacco combusto per potenziare la lotta al fumo - World Vapers&#039; Alliance","isPartOf":{"@id":"https:\/\/worldvapersalliance.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/worldvapersalliance.com\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\/#primaryimage"},"image":{"@id":"https:\/\/worldvapersalliance.com\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\/#primaryimage"},"thumbnailUrl":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2025\/08\/WVA-in-the-news.png","datePublished":"2023-10-17T11:43:26+00:00","dateModified":"2023-10-24T11:47:41+00:00","inLanguage":"da-DK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/worldvapersalliance.com\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\/"]}]},{"@type":"ImageObject","inLanguage":"da-DK","@id":"https:\/\/worldvapersalliance.com\/la-svezia-vuole-detassare-i-prodotti-alternativi-al-tabacco-combusto-per-potenziare-la-lotta-al-fumo\/#primaryimage","url":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2025\/08\/WVA-in-the-news.png","contentUrl":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2025\/08\/WVA-in-the-news.png","width":1264,"height":848},{"@type":"WebSite","@id":"https:\/\/worldvapersalliance.com\/#website","url":"https:\/\/worldvapersalliance.com\/","name":"World Vapers&#039; Alliance","description":"Det st\u00f8rste samfund af vapers","publisher":{"@id":"https:\/\/worldvapersalliance.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/worldvapersalliance.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"da-DK"},{"@type":"Organization","@id":"https:\/\/worldvapersalliance.com\/#organization","name":"World Vapers&#039; Alliance","url":"https:\/\/worldvapersalliance.com\/","logo":{"@type":"ImageObject","inLanguage":"da-DK","@id":"https:\/\/worldvapersalliance.com\/#\/schema\/logo\/image\/","url":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2022\/01\/WVA_RB_Fist_G.png","contentUrl":"https:\/\/worldvapersalliance.com\/wp-content\/uploads\/2022\/01\/WVA_RB_Fist_G.png","width":985,"height":1177,"caption":"World Vapers&#039; Alliance"},"image":{"@id":"https:\/\/worldvapersalliance.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/worldvapersalliance.com\/#\/schema\/person\/18484a6f20bcc6f70a2419c8babe017d","name":"World Vapers&#039; Alliance","image":{"@type":"ImageObject","inLanguage":"da-DK","@id":"https:\/\/secure.gravatar.com\/avatar\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/456bf795c7a47c9ac527a94da4bff150aa49e48726d69bee9937f8383cffa246?s=96&d=mm&r=g","caption":"World Vapers' Alliance"},"url":"https:\/\/worldvapersalliance.com\/da\/author\/wva\/"}]}},"_links":{"self":[{"href":"https:\/\/worldvapersalliance.com\/da\/wp-json\/wp\/v2\/posts\/4942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/worldvapersalliance.com\/da\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/worldvapersalliance.com\/da\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/worldvapersalliance.com\/da\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/worldvapersalliance.com\/da\/wp-json\/wp\/v2\/comments?post=4942"}],"version-history":[{"count":0,"href":"https:\/\/worldvapersalliance.com\/da\/wp-json\/wp\/v2\/posts\/4942\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/worldvapersalliance.com\/da\/wp-json\/wp\/v2\/media\/6394"}],"wp:attachment":[{"href":"https:\/\/worldvapersalliance.com\/da\/wp-json\/wp\/v2\/media?parent=4942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/worldvapersalliance.com\/da\/wp-json\/wp\/v2\/categories?post=4942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/worldvapersalliance.com\/da\/wp-json\/wp\/v2\/tags?post=4942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}